{"id":2036,"date":"2021-11-14T13:37:00","date_gmt":"2021-11-14T12:37:00","guid":{"rendered":"https:\/\/bewadesch.com\/?p=2036"},"modified":"2022-09-06T18:14:42","modified_gmt":"2022-09-06T16:14:42","slug":"kein-wille-zu-veraenderungen","status":"publish","type":"post","link":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/","title":{"rendered":"Kein Wille zu Ver\u00e4nderungen?!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ich zweifle immer mehr an den ehrlichen Bem\u00fchungen unserer politischen Vertreter zum Klimaschutz etc.. Wenn sich die Wirtschaftskammer nach den Verhandlungen zur CO2 Bepreisung damit br\u00fcstet, das es in \u00d6sterreich immer noch das &#8222;Dieselprivileg&#8220; gibt, kann kein Wille f\u00fcr positive Ver\u00e4nderungen vorhanden sein!! Neben der Inntalautobahn gibt es immer mehr &#8222;Billigtankstellen&#8220;(LKW-Diesel) die oftmals auch massive Verkehrsprobleme auf den Zufahrten ausl\u00f6sen. Durch solche Sonderaktionen werden die internationalen Fr\u00e4chter vermehrt auf die schon lange \u00fcberlastete Brennerstrecke gelockt. Auch Kerosin (Flugbenzin) ist von einer CO2 Besteuerung weiterhin befreit! Der Bev\u00f6lkerung wird erz\u00e4hlt, dass durch h\u00f6here Treibstoffpreise <strong>alle<\/strong> (??) Konsumg\u00fcter teurer werden m\u00fcssen! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Beim gro\u00dfen Klimagipfel in Glasgow wurde zwei Wochen lang nur &#8222;hei\u00dfe Luft&#8220; produziert. In der Abschlusserkl\u00e4rung wird die Welt zum Kohleausstieg aufgefordert(?). Auch sollen in Zukunft &#8222;ineffiziente&#8220; <strong>Subventionen<\/strong> f\u00fcr \u00d6l, Gas und Kohle gestrichen werden. Eine Veranstaltung  die viele Millionen(Euro) verschlingt bringt solche Ergebnisse zu Stande!!! Nachhaltigkeit sieht f\u00fcr mich ganz anders aus!!!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Geld(Wirtschaft) allein weiterhin die Welt regiert, mache ich mir ernsthafte Sorgen um unsere Zukunft!!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ich zweifle immer mehr an den ehrlichen Bem\u00fchungen unserer politischen Vertreter zum Klimaschutz etc.. Wenn sich die Wirtschaftskammer nach den Verhandlungen zur CO2 Bepreisung damit br\u00fcstet, das es in \u00d6sterreich immer noch das &#8222;Dieselprivileg&#8220; gibt, kann kein Wille f\u00fcr positive Ver\u00e4nderungen vorhanden sein!! Neben der Inntalautobahn gibt es immer mehr [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2037,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,18],"tags":[61,62],"class_list":["post-2036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-land-und-leute","tag-dieselprivileg","tag-kohleausstieg"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ich zweifle immer mehr an den ehrlichen Bem\u00fchungen unserer politischen Vertreter zum Klimaschutz etc.. Wenn sich die Wirtschaftskammer nach den Verhandlungen zur CO2 Bepreisung damit br\u00fcstet, das es in \u00d6sterreich immer noch das &quot;Dieselprivileg&quot; gibt, kann kein Wille f\u00fcr positive Ver\u00e4nderungen vorhanden sein!! Neben der Inntalautobahn gibt es immer mehr &quot;Billigtankstellen&quot;(LKW-Diesel) die oftmals auch massive\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Thomas\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"de_DE\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Bewahrung der Sch\u00f6pfung - Gemeinsam f\u00fcr eine lebenswerte Mutter Erde\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Kein Wille zu Ver\u00e4nderungen?! - Bewahrung der Sch\u00f6pfung\" \/>\n\t\t<meta property=\"og:description\" content=\"Ich zweifle immer mehr an den ehrlichen Bem\u00fchungen unserer politischen Vertreter zum Klimaschutz etc.. Wenn sich die Wirtschaftskammer nach den Verhandlungen zur CO2 Bepreisung damit br\u00fcstet, das es in \u00d6sterreich immer noch das &quot;Dieselprivileg&quot; gibt, kann kein Wille f\u00fcr positive Ver\u00e4nderungen vorhanden sein!! Neben der Inntalautobahn gibt es immer mehr &quot;Billigtankstellen&quot;(LKW-Diesel) die oftmals auch massive\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-11-14T12:37:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-09-06T16:14:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Kein Wille zu Ver\u00e4nderungen?! - Bewahrung der Sch\u00f6pfung\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ich zweifle immer mehr an den ehrlichen Bem\u00fchungen unserer politischen Vertreter zum Klimaschutz etc.. Wenn sich die Wirtschaftskammer nach den Verhandlungen zur CO2 Bepreisung damit br\u00fcstet, das es in \u00d6sterreich immer noch das &quot;Dieselprivileg&quot; gibt, kann kein Wille f\u00fcr positive Ver\u00e4nderungen vorhanden sein!! Neben der Inntalautobahn gibt es immer mehr &quot;Billigtankstellen&quot;(LKW-Diesel) die oftmals auch massive\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/2021\\\/11\\\/14\\\/kein-wille-zu-veraenderungen\\\/#blogposting\",\"name\":\"Kein Wille zu Ver\\u00e4nderungen?! - Bewahrung der Sch\\u00f6pfung\",\"headline\":\"Kein Wille zu Ver\\u00e4nderungen?!\",\"author\":{\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/author\\\/plankensteinerthgmail-com\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/bewadesch.com\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/bewadesch.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cat-kitten-pet-6706393.jpg\",\"width\":1280,\"height\":854,\"caption\":\"cat, kitten, pet-6706393.jpg\"},\"datePublished\":\"2021-11-14T13:37:00+01:00\",\"dateModified\":\"2022-09-06T18:14:42+02:00\",\"inLanguage\":\"de-AT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/2021\\\/11\\\/14\\\/kein-wille-zu-veraenderungen\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/2021\\\/11\\\/14\\\/kein-wille-zu-veraenderungen\\\/#webpage\"},\"articleSection\":\"Allgemein, Land und Leute, Dieselprivileg, Kohleausstieg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/2021\\\/11\\\/14\\\/kein-wille-zu-veraenderungen\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bewadesch.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bewadesch.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/category\\\/allgemein\\\/#listItem\",\"name\":\"Allgemein\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/category\\\/allgemein\\\/#listItem\",\"position\":2,\"name\":\"Allgemein\",\"item\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/category\\\/allgemein\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/2021\\\/11\\\/14\\\/kein-wille-zu-veraenderungen\\\/#listItem\",\"name\":\"Kein Wille zu Ver\\u00e4nderungen?!\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bewadesch.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/2021\\\/11\\\/14\\\/kein-wille-zu-veraenderungen\\\/#listItem\",\"position\":3,\"name\":\"Kein Wille zu Ver\\u00e4nderungen?!\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/category\\\/allgemein\\\/#listItem\",\"name\":\"Allgemein\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bewadesch.com\\\/#person\",\"name\":\"Thomas\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/2021\\\/11\\\/14\\\/kein-wille-zu-veraenderungen\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85f6fe65c28c15be609085ebb3930844f7971f74f4b2cfb2ea8eaa7cc56707dd?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Thomas\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/author\\\/plankensteinerthgmail-com\\\/#author\",\"url\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/author\\\/plankensteinerthgmail-com\\\/\",\"name\":\"Thomas\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/2021\\\/11\\\/14\\\/kein-wille-zu-veraenderungen\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85f6fe65c28c15be609085ebb3930844f7971f74f4b2cfb2ea8eaa7cc56707dd?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Thomas\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/2021\\\/11\\\/14\\\/kein-wille-zu-veraenderungen\\\/#webpage\",\"url\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/2021\\\/11\\\/14\\\/kein-wille-zu-veraenderungen\\\/\",\"name\":\"Kein Wille zu Ver\\u00e4nderungen?! - Bewahrung der Sch\\u00f6pfung\",\"description\":\"Ich zweifle immer mehr an den ehrlichen Bem\\u00fchungen unserer politischen Vertreter zum Klimaschutz etc.. Wenn sich die Wirtschaftskammer nach den Verhandlungen zur CO2 Bepreisung damit br\\u00fcstet, das es in \\u00d6sterreich immer noch das \\\"Dieselprivileg\\\" gibt, kann kein Wille f\\u00fcr positive Ver\\u00e4nderungen vorhanden sein!! Neben der Inntalautobahn gibt es immer mehr \\\"Billigtankstellen\\\"(LKW-Diesel) die oftmals auch massive\",\"inLanguage\":\"de-AT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bewadesch.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/2021\\\/11\\\/14\\\/kein-wille-zu-veraenderungen\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/author\\\/plankensteinerthgmail-com\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/author\\\/plankensteinerthgmail-com\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/bewadesch.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/cat-kitten-pet-6706393.jpg\",\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/2021\\\/11\\\/14\\\/kein-wille-zu-veraenderungen\\\/#mainImage\",\"width\":1280,\"height\":854,\"caption\":\"cat, kitten, pet-6706393.jpg\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bewadesch.com\\\/index.php\\\/2021\\\/11\\\/14\\\/kein-wille-zu-veraenderungen\\\/#mainImage\"},\"datePublished\":\"2021-11-14T13:37:00+01:00\",\"dateModified\":\"2022-09-06T18:14:42+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bewadesch.com\\\/#website\",\"url\":\"https:\\\/\\\/bewadesch.com\\\/\",\"name\":\"Bewahrung der Sch\\u00f6pfung\",\"description\":\"Gemeinsam f\\u00fcr eine lebenswerte Mutter Erde\",\"inLanguage\":\"de-AT\",\"publisher\":{\"@id\":\"https:\\\/\\\/bewadesch.com\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Kein Wille zu Ver\u00e4nderungen?! - Bewahrung der Sch\u00f6pfung","description":"Ich zweifle immer mehr an den ehrlichen Bem\u00fchungen unserer politischen Vertreter zum Klimaschutz etc.. Wenn sich die Wirtschaftskammer nach den Verhandlungen zur CO2 Bepreisung damit br\u00fcstet, das es in \u00d6sterreich immer noch das \"Dieselprivileg\" gibt, kann kein Wille f\u00fcr positive Ver\u00e4nderungen vorhanden sein!! Neben der Inntalautobahn gibt es immer mehr \"Billigtankstellen\"(LKW-Diesel) die oftmals auch massive","canonical_url":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/#blogposting","name":"Kein Wille zu Ver\u00e4nderungen?! - Bewahrung der Sch\u00f6pfung","headline":"Kein Wille zu Ver\u00e4nderungen?!","author":{"@id":"https:\/\/bewadesch.com\/index.php\/author\/plankensteinerthgmail-com\/#author"},"publisher":{"@id":"https:\/\/bewadesch.com\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/bewadesch.com\/wp-content\/uploads\/2021\/11\/cat-kitten-pet-6706393.jpg","width":1280,"height":854,"caption":"cat, kitten, pet-6706393.jpg"},"datePublished":"2021-11-14T13:37:00+01:00","dateModified":"2022-09-06T18:14:42+02:00","inLanguage":"de-AT","mainEntityOfPage":{"@id":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/#webpage"},"isPartOf":{"@id":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/#webpage"},"articleSection":"Allgemein, Land und Leute, Dieselprivileg, Kohleausstieg"},{"@type":"BreadcrumbList","@id":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/bewadesch.com#listItem","position":1,"name":"Home","item":"https:\/\/bewadesch.com","nextItem":{"@type":"ListItem","@id":"https:\/\/bewadesch.com\/index.php\/category\/allgemein\/#listItem","name":"Allgemein"}},{"@type":"ListItem","@id":"https:\/\/bewadesch.com\/index.php\/category\/allgemein\/#listItem","position":2,"name":"Allgemein","item":"https:\/\/bewadesch.com\/index.php\/category\/allgemein\/","nextItem":{"@type":"ListItem","@id":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/#listItem","name":"Kein Wille zu Ver\u00e4nderungen?!"},"previousItem":{"@type":"ListItem","@id":"https:\/\/bewadesch.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/#listItem","position":3,"name":"Kein Wille zu Ver\u00e4nderungen?!","previousItem":{"@type":"ListItem","@id":"https:\/\/bewadesch.com\/index.php\/category\/allgemein\/#listItem","name":"Allgemein"}}]},{"@type":"Person","@id":"https:\/\/bewadesch.com\/#person","name":"Thomas","image":{"@type":"ImageObject","@id":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/85f6fe65c28c15be609085ebb3930844f7971f74f4b2cfb2ea8eaa7cc56707dd?s=96&d=mm&r=g","width":96,"height":96,"caption":"Thomas"}},{"@type":"Person","@id":"https:\/\/bewadesch.com\/index.php\/author\/plankensteinerthgmail-com\/#author","url":"https:\/\/bewadesch.com\/index.php\/author\/plankensteinerthgmail-com\/","name":"Thomas","image":{"@type":"ImageObject","@id":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/85f6fe65c28c15be609085ebb3930844f7971f74f4b2cfb2ea8eaa7cc56707dd?s=96&d=mm&r=g","width":96,"height":96,"caption":"Thomas"}},{"@type":"WebPage","@id":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/#webpage","url":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/","name":"Kein Wille zu Ver\u00e4nderungen?! - Bewahrung der Sch\u00f6pfung","description":"Ich zweifle immer mehr an den ehrlichen Bem\u00fchungen unserer politischen Vertreter zum Klimaschutz etc.. Wenn sich die Wirtschaftskammer nach den Verhandlungen zur CO2 Bepreisung damit br\u00fcstet, das es in \u00d6sterreich immer noch das \"Dieselprivileg\" gibt, kann kein Wille f\u00fcr positive Ver\u00e4nderungen vorhanden sein!! Neben der Inntalautobahn gibt es immer mehr \"Billigtankstellen\"(LKW-Diesel) die oftmals auch massive","inLanguage":"de-AT","isPartOf":{"@id":"https:\/\/bewadesch.com\/#website"},"breadcrumb":{"@id":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/#breadcrumblist"},"author":{"@id":"https:\/\/bewadesch.com\/index.php\/author\/plankensteinerthgmail-com\/#author"},"creator":{"@id":"https:\/\/bewadesch.com\/index.php\/author\/plankensteinerthgmail-com\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/bewadesch.com\/wp-content\/uploads\/2021\/11\/cat-kitten-pet-6706393.jpg","@id":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/#mainImage","width":1280,"height":854,"caption":"cat, kitten, pet-6706393.jpg"},"primaryImageOfPage":{"@id":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/#mainImage"},"datePublished":"2021-11-14T13:37:00+01:00","dateModified":"2022-09-06T18:14:42+02:00"},{"@type":"WebSite","@id":"https:\/\/bewadesch.com\/#website","url":"https:\/\/bewadesch.com\/","name":"Bewahrung der Sch\u00f6pfung","description":"Gemeinsam f\u00fcr eine lebenswerte Mutter Erde","inLanguage":"de-AT","publisher":{"@id":"https:\/\/bewadesch.com\/#person"}}]},"og:locale":"de_DE","og:site_name":"Bewahrung der Sch\u00f6pfung - Gemeinsam f\u00fcr eine lebenswerte Mutter Erde","og:type":"article","og:title":"Kein Wille zu Ver\u00e4nderungen?! - Bewahrung der Sch\u00f6pfung","og:description":"Ich zweifle immer mehr an den ehrlichen Bem\u00fchungen unserer politischen Vertreter zum Klimaschutz etc.. Wenn sich die Wirtschaftskammer nach den Verhandlungen zur CO2 Bepreisung damit br\u00fcstet, das es in \u00d6sterreich immer noch das &quot;Dieselprivileg&quot; gibt, kann kein Wille f\u00fcr positive Ver\u00e4nderungen vorhanden sein!! Neben der Inntalautobahn gibt es immer mehr &quot;Billigtankstellen&quot;(LKW-Diesel) die oftmals auch massive","og:url":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/","article:published_time":"2021-11-14T12:37:00+00:00","article:modified_time":"2022-09-06T16:14:42+00:00","twitter:card":"summary","twitter:title":"Kein Wille zu Ver\u00e4nderungen?! - Bewahrung der Sch\u00f6pfung","twitter:description":"Ich zweifle immer mehr an den ehrlichen Bem\u00fchungen unserer politischen Vertreter zum Klimaschutz etc.. Wenn sich die Wirtschaftskammer nach den Verhandlungen zur CO2 Bepreisung damit br\u00fcstet, das es in \u00d6sterreich immer noch das &quot;Dieselprivileg&quot; gibt, kann kein Wille f\u00fcr positive Ver\u00e4nderungen vorhanden sein!! Neben der Inntalautobahn gibt es immer mehr &quot;Billigtankstellen&quot;(LKW-Diesel) die oftmals auch massive"},"aioseo_meta_data":{"post_id":"2036","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"},\"blockGraphs\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-11-14 12:37:01","updated":"2025-06-04 18:53:58","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/bewadesch.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/bewadesch.com\/index.php\/category\/allgemein\/\" title=\"Allgemein\">Allgemein<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tKein Wille zu Ver\u00e4nderungen?!\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/bewadesch.com"},{"label":"Allgemein","link":"https:\/\/bewadesch.com\/index.php\/category\/allgemein\/"},{"label":"Kein Wille zu Ver\u00e4nderungen?!","link":"https:\/\/bewadesch.com\/index.php\/2021\/11\/14\/kein-wille-zu-veraenderungen\/"}],"_links":{"self":[{"href":"https:\/\/bewadesch.com\/index.php\/wp-json\/wp\/v2\/posts\/2036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bewadesch.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bewadesch.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bewadesch.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bewadesch.com\/index.php\/wp-json\/wp\/v2\/comments?post=2036"}],"version-history":[{"count":1,"href":"https:\/\/bewadesch.com\/index.php\/wp-json\/wp\/v2\/posts\/2036\/revisions"}],"predecessor-version":[{"id":2038,"href":"https:\/\/bewadesch.com\/index.php\/wp-json\/wp\/v2\/posts\/2036\/revisions\/2038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bewadesch.com\/index.php\/wp-json\/wp\/v2\/media\/2037"}],"wp:attachment":[{"href":"https:\/\/bewadesch.com\/index.php\/wp-json\/wp\/v2\/media?parent=2036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bewadesch.com\/index.php\/wp-json\/wp\/v2\/categories?post=2036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bewadesch.com\/index.php\/wp-json\/wp\/v2\/tags?post=2036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}